{"id":34483,"date":"2024-09-10T19:43:36","date_gmt":"2024-09-10T17:43:36","guid":{"rendered":"http:\/\/causedupeuple.net\/wp68\/?p=4483"},"modified":"2024-09-10T19:43:54","modified_gmt":"2024-09-10T17:43:54","slug":"la-depakine-un-scandale-pharmaceutique-chez-sanofi","status":"publish","type":"post","link":"http:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/","title":{"rendered":"La D\u00e9pakine, un scandale pharmaceutique chez Sanofi"},"content":{"rendered":"\n<p>Ce lundi 9 septembre, apr\u00e8s 13 ans de combat, Marine Martin, m\u00e8re de famille \u00e9pileptique, a obtenu du tribunal judiciaire de Paris la reconnaissance officielle de la responsabilit\u00e9 de Sanofi dans le handicap de ses enfants et une r\u00e9paration financi\u00e8re.<\/p>\n\n\n\n<p>Reprenons chronologiquement son histoire : cette m\u00e8re de famille est plac\u00e9e sous traitement anti \u00e9pileptique, la D\u00e9pakine \u00e0 l&rsquo;enfance. <br>Entre 1998 et 2002, Marine a 2 enfants. Tous deux naissent assez lourdement handicap\u00e9s.<br>Sa fille a\u00een\u00e9e, Salom\u00e9, souffre de malformations physiques et de troubles cognitifs, visuels et dyspraxiques.<br>Le cadet, Florent, na\u00eet avec de multiples malformations physiques qui ont entra\u00een\u00e9 plusieurs op\u00e9rations, et souffre de troubles du l&rsquo;attention, du langage et d&rsquo;un autisme de type Asperger.<\/p>\n\n\n\n<p>Commercialis\u00e9 depuis 1967, la D\u00e9pakine pourrait avoir bris\u00e9 la vie de milliers de familles : selon l&rsquo;Agence Nationale de S\u00e9curit\u00e9 du M\u00e9dicament, le principe actif de la D\u00e9pakine pourrait avoir caus\u00e9 des malformations physiques chez 4000 enfants, et des troubles neurod\u00e9veloppementaux chez 30 000.<\/p>\n\n\n\n<p>Loin de reconna\u00eetre une quelconque responsabilit\u00e9, le monopole pharmaceutique Sanofi n&rsquo;a pendant des ann\u00e9e fait preuve que de m\u00e9pris \u00e0 l&rsquo;\u00e9gard des victimes.<br>Alors que la litt\u00e9rature scientifique fait mention des malformations physiques que peut engendrer le valproate de sodium d\u00e8s 1984, et d\u00e8s 2001 pour les troubles neurod\u00e9veloppementaux, Sanofi n&rsquo;a int\u00e9gr\u00e9 ses mentions \u00e0 la notice de son m\u00e9dicament qu&rsquo;en 2006, mettant par son omission volontaire en danger tous les patients trait\u00e9s par la D\u00e9pakine.<\/p>\n\n\n\n<p>Le tribunal judiciaire avait d\u00e9j\u00e0 tranch\u00e9 en 2022, reconnaissant la culpabilit\u00e9 de Sanofi, conscient du manquement d&rsquo;informations. Il vient de condamner il y a quelques jours le monopole pharmaceutique \u00e0 verser 285 000\u20ac \u00e0 Marine et ses 2 enfants.<br>Sanofi risque aussi de devoir rembourser plusieurs dizaines de millions d&rsquo;euros \u00e0 l&rsquo;Etat.<\/p>\n\n\n\n<p>285 000\u20ac : cest le prix pour 3 (au moins !) vies bris\u00e9es dans ce foyer selon la justice fran\u00e7aise. Toute l&rsquo;anxi\u00e9t\u00e9, la souffrance, les soins continus auxquels continue d&rsquo;\u00eatre d\u00e9pendant Florent, pour l&rsquo;Etat fran\u00e7ais tout cela se quantifie financi\u00e8rement, par une somme ridicule.<br>Cette \u00ab\u00a0compensation\u00a0\u00bb est \u00e0 mettre en parall\u00e8le avec les 43 milliards de dollars de chiffre d&rsquo;affaires de l&rsquo;entreprise en 2023 !<\/p>\n\n\n\n<p>Aujourd&rsquo;hui, dans un pays imp\u00e9rialiste comme la France, un monopole pharmaceutique peut d\u00e9truire impun\u00e9ment la vie de milliers de personnes d\u00e9j\u00e0 fragiles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce lundi 9 septembre, apr\u00e8s 13 ans de combat, Marine Martin, m\u00e8re de famille \u00e9pileptique, a obtenu du tribunal judiciaire de Paris la reconnaissance officielle de la responsabilit\u00e9 de Sanofi dans le handicap de ses enfants et une r\u00e9paration financi\u00e8re. Reprenons chronologiquement son histoire : cette m\u00e8re de famille est plac\u00e9e sous traitement anti \u00e9pileptique, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":34484,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[126,88,380,381,382],"class_list":["post-34483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-crimes-contre-le-peuple","tag-crise-de-limperialisme","tag-pharmaceutique","tag-proces","tag-sanofi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La D\u00e9pakine, un scandale pharmaceutique chez Sanofi - La Cause du Peuple<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La D\u00e9pakine, un scandale pharmaceutique chez Sanofi - La Cause du Peuple\" \/>\n<meta property=\"og:description\" content=\"Ce lundi 9 septembre, apr\u00e8s 13 ans de combat, Marine Martin, m\u00e8re de famille \u00e9pileptique, a obtenu du tribunal judiciaire de Paris la reconnaissance officielle de la responsabilit\u00e9 de Sanofi dans le handicap de ses enfants et une r\u00e9paration financi\u00e8re. Reprenons chronologiquement son histoire : cette m\u00e8re de famille est plac\u00e9e sous traitement anti \u00e9pileptique, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/\" \/>\n<meta property=\"og:site_name\" content=\"La Cause du Peuple\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CauseDuPeupleCDP\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-10T17:43:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-10T17:43:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Cause_du_Peuple\" \/>\n<meta name=\"twitter:site\" content=\"@Cause_du_Peuple\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2024\\\/09\\\/10\\\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2024\\\/09\\\/10\\\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La D\u00e9pakine, un scandale pharmaceutique chez Sanofi\",\"datePublished\":\"2024-09-10T17:43:36+00:00\",\"dateModified\":\"2024-09-10T17:43:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2024\\\/09\\\/10\\\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\\\/\"},\"wordCount\":408,\"publisher\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2024\\\/09\\\/10\\\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"crimes contre le peuple\",\"crise de l&#039;imperialisme\",\"Pharmaceutique\",\"Proc\u00e8s\",\"Sanofi\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2024\\\/09\\\/10\\\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\\\/\",\"url\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2024\\\/09\\\/10\\\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\\\/\",\"name\":\"La D\u00e9pakine, un scandale pharmaceutique chez Sanofi - La Cause du Peuple\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2024\\\/09\\\/10\\\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2024\\\/09\\\/10\\\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2024-09-10T17:43:36+00:00\",\"dateModified\":\"2024-09-10T17:43:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2024\\\/09\\\/10\\\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2024\\\/09\\\/10\\\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2024\\\/09\\\/10\\\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"A view of the French pharmaceutical Sanofi factory in Mourenx, south western France is pictured on October 16, 2018, which had been shut down in July over toxic pollution and partially repopend in mid-August. (Photo by IROZ GAIZKA \\\/ AFP)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2024\\\/09\\\/10\\\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La D\u00e9pakine, un scandale pharmaceutique chez Sanofi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#website\",\"url\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/\",\"name\":\"La Cause du Peuple\",\"description\":\"Media prol\u00e9taire, anti-imp\u00e9rialiste et r\u00e9volutionnaire !\",\"publisher\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#organization\",\"name\":\"La Cause du Peuple\",\"url\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/causedupeuple.net\\\/wp68\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo-CDP-1ligne-blanc.png\",\"contentUrl\":\"http:\\\/\\\/causedupeuple.net\\\/wp68\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo-CDP-1ligne-blanc.png\",\"width\":1454,\"height\":200,\"caption\":\"La Cause du Peuple\"},\"image\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CauseDuPeupleCDP\",\"https:\\\/\\\/x.com\\\/Cause_du_Peuple\",\"https:\\\/\\\/www.instagram.com\\\/cause_du_peuple\\\/\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"http:\\\/\\\/causedupeuple.net\\\/wp68\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La D\u00e9pakine, un scandale pharmaceutique chez Sanofi - La Cause du Peuple","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/","og_locale":"fr_FR","og_type":"article","og_title":"La D\u00e9pakine, un scandale pharmaceutique chez Sanofi - La Cause du Peuple","og_description":"Ce lundi 9 septembre, apr\u00e8s 13 ans de combat, Marine Martin, m\u00e8re de famille \u00e9pileptique, a obtenu du tribunal judiciaire de Paris la reconnaissance officielle de la responsabilit\u00e9 de Sanofi dans le handicap de ses enfants et une r\u00e9paration financi\u00e8re. Reprenons chronologiquement son histoire : cette m\u00e8re de famille est plac\u00e9e sous traitement anti \u00e9pileptique, [&hellip;]","og_url":"https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/","og_site_name":"La Cause du Peuple","article_publisher":"https:\/\/www.facebook.com\/CauseDuPeupleCDP","article_published_time":"2024-09-10T17:43:36+00:00","article_modified_time":"2024-09-10T17:43:54+00:00","twitter_card":"summary_large_image","twitter_creator":"@Cause_du_Peuple","twitter_site":"@Cause_du_Peuple","twitter_misc":{"\u00c9crit par":"","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/#article","isPartOf":{"@id":"https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/"},"author":{"name":"","@id":""},"headline":"La D\u00e9pakine, un scandale pharmaceutique chez Sanofi","datePublished":"2024-09-10T17:43:36+00:00","dateModified":"2024-09-10T17:43:54+00:00","mainEntityOfPage":{"@id":"https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/"},"wordCount":408,"publisher":{"@id":"https:\/\/causedupeuple.net\/wp68\/#organization"},"image":{"@id":"https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/#primaryimage"},"thumbnailUrl":"","keywords":["crimes contre le peuple","crise de l&#039;imperialisme","Pharmaceutique","Proc\u00e8s","Sanofi"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/","url":"https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/","name":"La D\u00e9pakine, un scandale pharmaceutique chez Sanofi - La Cause du Peuple","isPartOf":{"@id":"https:\/\/causedupeuple.net\/wp68\/#website"},"primaryImageOfPage":{"@id":"https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/#primaryimage"},"image":{"@id":"https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/#primaryimage"},"thumbnailUrl":"","datePublished":"2024-09-10T17:43:36+00:00","dateModified":"2024-09-10T17:43:54+00:00","breadcrumb":{"@id":"https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/#primaryimage","url":"","contentUrl":"","caption":"A view of the French pharmaceutical Sanofi factory in Mourenx, south western France is pictured on October 16, 2018, which had been shut down in July over toxic pollution and partially repopend in mid-August. (Photo by IROZ GAIZKA \/ AFP)"},{"@type":"BreadcrumbList","@id":"https:\/\/causedupeuple.net\/wp68\/2024\/09\/10\/la-depakine-un-scandale-pharmaceutique-chez-sanofi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/causedupeuple.net\/wp68\/"},{"@type":"ListItem","position":2,"name":"La D\u00e9pakine, un scandale pharmaceutique chez Sanofi"}]},{"@type":"WebSite","@id":"https:\/\/causedupeuple.net\/wp68\/#website","url":"https:\/\/causedupeuple.net\/wp68\/","name":"La Cause du Peuple","description":"Media prol\u00e9taire, anti-imp\u00e9rialiste et r\u00e9volutionnaire !","publisher":{"@id":"https:\/\/causedupeuple.net\/wp68\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/causedupeuple.net\/wp68\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/causedupeuple.net\/wp68\/#organization","name":"La Cause du Peuple","url":"https:\/\/causedupeuple.net\/wp68\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/causedupeuple.net\/wp68\/#\/schema\/logo\/image\/","url":"http:\/\/causedupeuple.net\/wp68\/wp-content\/uploads\/2026\/03\/Logo-CDP-1ligne-blanc.png","contentUrl":"http:\/\/causedupeuple.net\/wp68\/wp-content\/uploads\/2026\/03\/Logo-CDP-1ligne-blanc.png","width":1454,"height":200,"caption":"La Cause du Peuple"},"image":{"@id":"https:\/\/causedupeuple.net\/wp68\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CauseDuPeupleCDP","https:\/\/x.com\/Cause_du_Peuple","https:\/\/www.instagram.com\/cause_du_peuple\/"]},{"@type":"Person","@id":"","url":"http:\/\/causedupeuple.net\/wp68\/author\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/posts\/34483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/comments?post=34483"}],"version-history":[{"count":0,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/posts\/34483\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/media\/34484"}],"wp:attachment":[{"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/media?parent=34483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/categories?post=34483"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/tags?post=34483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}