{"id":38525,"date":"2026-04-30T11:19:43","date_gmt":"2026-04-30T10:19:43","guid":{"rendered":"https:\/\/www.causedupeuple.net\/?p=38068"},"modified":"2026-04-30T11:19:43","modified_gmt":"2026-04-30T10:19:43","slug":"parti-communiste-des-philippines-sur-le-massacre-de-toboso","status":"publish","type":"post","link":"http:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/","title":{"rendered":"Parti Communiste des Philippines\u00a0: Sur le massacre de Toboso"},"content":{"rendered":"\n<p><em>Nous partageons ici une traduction non officielle d&rsquo;un <a href=\"https:\/\/philippinerevolution.nu\/statements\/on-the-toboso-massacre\/\">communiqu\u00e9 du Parti Communiste des Philippines<\/a>.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><strong>Marco Valbuena | Directeur de l\u2019information | Parti Communiste des Philippines | 27 avril 2026<\/strong><\/p>\n\n\n\n<p>Nous condamnons avec la plus grande fermet\u00e9 les Forces arm\u00e9es des Philippines, en particulier le 79e bataillon d\u2019infanterie, pour le massacre aveugle et disproportionn\u00e9 de 19 personnes, parmi lesquelles figuraient des combattants rouges de la Nouvelle Arm\u00e9e populaire (NPA) ainsi que des civils non arm\u00e9s, perp\u00e9tr\u00e9 le 19 avril dernier dans le Barangay de Salamanca, dans la ville de Toboso, province de Negros Occidental.<\/p>\n\n\n\n<p>Nous rendons hommage \u00e0 l\u2019escouade de dix combattants rouges de la NPA qui ont combattu les fascistes jusqu\u2019\u00e0 leur dernier souffle. Il s\u2019agit de :<\/p>\n\n\n\n<p>1. Roger Fabillar (Ka Tapang), qui a servi comme commandant de la NPA sur le front nord de Negros<\/p>\n\n\n\n<p>2. Sonny Boy Caramihan, 28 ans, originaire de Barangay Bagonbon, ville de San Carlos ;<\/p>\n\n\n\n<p>3. Ren\u00e9 Villarin Sr, 57 ans, du barangay Marcelo, \u00e0 Calatrava, chef d\u2019escouade ;<\/p>\n\n\n\n<p>4. Pedro Bonghanoy, officier m\u00e9dical, du barangay Libertad, \u00e0 Escalante ;<\/p>\n\n\n\n<p>5. Arnel Javoc, 32 ans, originaire du barangay Lalong, \u00e0 Calatrava ;<\/p>\n\n\n\n<p>6. Joros Caramihan y Ramos, 18 ans, originaire de Don Salvador Benedicto ;<\/p>\n\n\n\n<p>7. Maria Clarita Branzuel Blanco (Ka Sanim\/Pat), instructrice politique ; et<\/p>\n\n\n\n<p>8. Genevieve Balora (Ka Raia), originaire de Bacolod City, cadre du Parti au niveau du district<\/p>\n\n\n\n<p>9. Labskie Purisimia Enustacion, 33 ans, de Sitio Tinibawan, Barangay Bug-ang, Toboso<\/p>\n\n\n\n<p>10. Jocel Gimang, 18 ans, de Sitio Bautista, Barangay Malasibog, Escalante City<\/p>\n\n\n\n<p>Nous exprimons notre profonde affection aux proches et aux camarades des combattants rouges de la NPA qui ont perdu la vie. Leur disparition nous p\u00e8se lourdement sur le c\u0153ur. En tant que guerriers r\u00e9volutionnaires, ils ont tous servi de mani\u00e8re d\u00e9sint\u00e9ress\u00e9e le peuple philippin, en particulier les paysans et les ouvriers agricoles opprim\u00e9s et exploit\u00e9s de Negros. Ils \u00e9taient profond\u00e9ment aim\u00e9s par les masses. Bravant la r\u00e9pression militaire qui s&rsquo;abattait sur leurs communaut\u00e9s, les habitants de Toboso et de Calatrava se sont rassembl\u00e9s en longs cort\u00e8ges pour accompagner leurs combattants rouges bien-aim\u00e9s vers leur derni\u00e8re demeure, afin d&rsquo;exprimer leur profond respect et leur immense gratitude.<\/p>\n\n\n\n<p>La Nouvelle Arm\u00e9e Populaire a subi une d\u00e9faite tactique ce jour fatidique, mais elle reste lucide et d\u00e9termin\u00e9e \u00e0 avancer sur la voie r\u00e9volutionnaire vers la victoire strat\u00e9gique. La position courageuse et l\u2019h\u00e9ro\u00efsme de ses combattants rouges \u00e0 Toboso inspirent les masses opprim\u00e9es \u00e0 se soulever et \u00e0 r\u00e9sister par la r\u00e9volution arm\u00e9e. Le sang vers\u00e9 par les guerriers tomb\u00e9s au combat lors de leur derni\u00e8re bataille nourrit le terreau de la guerre populaire, d\u2019o\u00f9 jailliront encore plus de combattants rouges de la Nouvelle Arm\u00e9e Populaire.<\/p>\n\n\n\n<p>Nous adressons \u00e9galement nos sinc\u00e8res condol\u00e9ances aux familles et aux proches de :<br><br>1. Roel Sabillo, 19 ans, habitant du barangay Tabunac, \u00e0 Toboso<\/p>\n\n\n\n<p>2. R.J. Nichole Ledesma, 30 ans, journaliste communautaire de Bacolod City<\/p>\n\n\n\n<p>3. Alyssa Alano, conseill\u00e8re au Conseil \u00e9tudiant de l&rsquo;UP Diliman<\/p>\n\n\n\n<p>4. Maureen Keil Santuyo, 24 ans, membre du R\u00e9seau national des d\u00e9fenseurs de la r\u00e9forme agraire (NNARA-Youth)<\/p>\n\n\n\n<p>5. Errol Wendel, 24 ans, membre de l&rsquo;Unyon ng mga Manggagawa sa Agrikultura<\/p>\n\n\n\n<p>6. Jemina Gumadlas, 15 ans, habitante de Sitio Plarending, Barangay Salamanca, Toboso<\/p>\n\n\n\n<p>7. Lyle Prijoles, 40 ans, de la Coalition internationale pour les droits de l\u2019homme aux Philippines, originaire de San Francisco, Californie (\u00c9tats-Unis)<\/p>\n\n\n\n<p>8. Kai Sorem, 26 ans, originaire de Seattle, Washington (\u00c9tats-Unis)<\/p>\n\n\n\n<p>9. Dexter Patajo, 17 ans, de Sitio Buklog, Barangay Lalong, Calatrava, Negros Occidental<\/p>\n\n\n\n<p>D&rsquo;apr\u00e8s les premi\u00e8res informations que nous avons recueillies, ils ont \u00e9t\u00e9 tu\u00e9s alors qu&rsquo;ils \u00e9taient d\u00e9sarm\u00e9s ou non-combattants. Parmi eux se trouvent un journaliste, un dirigeant \u00e9tudiant, des organisateurs paysans, des d\u00e9fenseurs des droits humains \u00e9trangers et des habitants locaux. Deux des victimes \u00e9taient des enfants.<\/p>\n\n\n\n<p>Nous rendons hommage aux victimes du massacre de Toboso, tant aux combattants rouges qu\u2019\u00e0 tous ceux qui ont choisi de mani\u00e8re d\u00e9sint\u00e9ress\u00e9e de mettre leur force, leurs connaissances et leurs comp\u00e9tences au service des masses opprim\u00e9es et exploit\u00e9es. Suivons la voie qu\u2019ils ont emprunt\u00e9e pour le salut de la nation.<\/p>\n\n\n\n<p>Les officiers et les troupes op\u00e9rationnelles des Forces arm\u00e9es des Philippines (AFP) se sont rendus coupables de meurtres d\u00e9lib\u00e9r\u00e9s et aveugles. Ils doivent \u00eatre amen\u00e9s \u00e0 rendre des comptes et punis pour leurs crimes graves au regard du droit international humanitaire.<\/p>\n\n\n\n<p>Des s\u00e9quences vid\u00e9o provenant des cam\u00e9ras des drones de l\u2019AFP ont \u00e9galement fait surface sur les r\u00e9seaux sociaux, montrant que Ka Tapang \u00e9tait vivant et apparemment incapable de livrer bataille. Cela indique qu\u2019il a \u00e9t\u00e9 sommairement ex\u00e9cut\u00e9 par les fascistes, au lieu d\u2019\u00eatre fait prisonnier de guerre. Nous exhortons les autres membres consciencieux de l\u2019AFP qui poss\u00e8dent d\u2019autres images de drones \u00e0 les faire sortir clandestinement et \u00e0 se manifester pour r\u00e9v\u00e9ler le v\u00e9ritable r\u00e9cit de la mani\u00e8re dont ces crimes brutaux ont \u00e9t\u00e9 commis, contrairement aux r\u00e9cits invent\u00e9s par leurs sup\u00e9rieurs.<\/p>\n\n\n\n<p>L&rsquo;AFP tente d\u00e9sesp\u00e9r\u00e9ment de dissimuler ses crimes, en inventant des faits d\u00e9form\u00e9s pour \u00e9tayer ses mensonges. L&rsquo;affirmation initiale de l&rsquo;AFP selon laquelle sept armes \u00e0 feu avaient \u00e9t\u00e9 r\u00e9cup\u00e9r\u00e9es sur les lieux a ensuite \u00e9t\u00e9 \u00ab mise \u00e0 jour \u00bb pour passer \u00e0 20 (puis 24), afin de faire croire que toutes les personnes tu\u00e9es \u00e9taient des combattants arm\u00e9s.<\/p>\n\n\n\n<p>L&rsquo;AFP a \u00e9vacu\u00e9 de force les habitants locaux, puis a boucl\u00e9 la zone afin d&rsquo;imposer un black-out m\u00e9diatique et d&#8217;emp\u00eacher les m\u00e9dias et les groupes ind\u00e9pendants de mener des entretiens et une enqu\u00eate efficace sur le massacre. Quelques jours plus tard, un groupe organis\u00e9 par l&rsquo;arm\u00e9e a \u00e9t\u00e9 autoris\u00e9 \u00e0 mener sa propre \u00ab mission d&rsquo;enqu\u00eate \u00bb, une mascarade destin\u00e9e \u00e0 fabriquer de toutes pi\u00e8ces un r\u00e9cit valid\u00e9 par l&rsquo;AFP, conforme \u00e0 leur version officielle d&rsquo;une \u00ab op\u00e9ration l\u00e9gitime \u00bb.<\/p>\n\n\n\n<p>Incr\u00e9dules, diverses personnalit\u00e9s et divers secteurs ont r\u00e9clam\u00e9 une enqu\u00eate ind\u00e9pendante. La Commission des droits de l\u2019homme a annonc\u00e9 qu\u2019elle en m\u00e8nerait une, bien qu\u2019elle ait d\u00e9j\u00e0 fait des d\u00e9clarations vides de sens similaires par le pass\u00e9. Rappelons-nous comment elle avait promis d\u2019enqu\u00eater sur le massacre de la famille Fausto en 2023 \u00e0 Himamaylan City, dans la province de Negros Occidental, impliquant le 94e bataillon d\u2019infanterie de l\u2019AFP, mais n\u2019a rien produit de substantiel pr\u00e8s de trois ans apr\u00e8s.<\/p>\n\n\n\n<p>Les larges masses du peuple philippin subissent des formes d\u2019oppression et d\u2019exploitation de plus en plus graves face \u00e0 l\u2019aggravation de la crise sous le r\u00e9gime fasciste et fantoche de Marcos. Marcos a ordonn\u00e9 \u00e0 ses sbires arm\u00e9s de l\u2019AFP et d\u2019ELCAC <em>[Groupe national pour mettre fin au conflit arm\u00e9 communiste local, ndlt.]<\/em> d\u2019intensifier leurs attaques contre le peuple sous le pr\u00e9texte de la \u00ab paix et du d\u00e9veloppement \u00bb. \u00c0 l\u2019instar de son p\u00e8re dictateur, Marcos Jr. recourt \u00e0 des tactiques de terreur pour soumettre la population \u00e0 la r\u00e9pression politique, en particulier dans les campagnes, o\u00f9 r\u00e8gne la loi martiale.<\/p>\n\n\n\n<p>Le terrorisme d&rsquo;\u00c9tat n&rsquo;a jamais r\u00e9ussi \u00e0 briser la volont\u00e9 du peuple. Les attaques du r\u00e9gime de Marcos ne parviendront pas \u00e0 emp\u00eacher le peuple de riposter. Au contraire, sa brutalit\u00e9 fasciste ne fait que renforcer la d\u00e9termination du peuple, rendant ind\u00e9niables la justesse et la n\u00e9cessit\u00e9 de mener une r\u00e9volution arm\u00e9e.<\/p>\n\n\n\n<p>La Nouvelle Arm\u00e9e Populaire reste in\u00e9branlable dans sa d\u00e9termination \u00e0 rendre justice r\u00e9volutionnaire \u00e0 toutes les victimes du massacre de Toboso.<\/p>\n\n\n\n<p>Les flammes de la guerre populaire continueront de faire rage et de se propager \u00e0 travers le pays, car l\u2019aspiration du peuple philippin \u00e0 la libert\u00e9 nationale et \u00e0 une v\u00e9ritable d\u00e9mocratie br\u00fble avec force dans ses c\u0153urs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous partageons ici une traduction non officielle d&rsquo;un communiqu\u00e9 du Parti Communiste des Philippines. Marco Valbuena | Directeur de l\u2019information | Parti Communiste des Philippines | 27 avril 2026 Nous condamnons avec la plus grande fermet\u00e9 les Forces arm\u00e9es des Philippines, en particulier le 79e bataillon d\u2019infanterie, pour le massacre aveugle et disproportionn\u00e9 de 19 [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":38592,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-38525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-international"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parti Communiste des Philippines\u00a0: Sur le massacre de Toboso - La Cause du Peuple<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parti Communiste des Philippines\u00a0: Sur le massacre de Toboso - La Cause du Peuple\" \/>\n<meta property=\"og:description\" content=\"Nous partageons ici une traduction non officielle d&rsquo;un communiqu\u00e9 du Parti Communiste des Philippines. Marco Valbuena | Directeur de l\u2019information | Parti Communiste des Philippines | 27 avril 2026 Nous condamnons avec la plus grande fermet\u00e9 les Forces arm\u00e9es des Philippines, en particulier le 79e bataillon d\u2019infanterie, pour le massacre aveugle et disproportionn\u00e9 de 19 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/\" \/>\n<meta property=\"og:site_name\" content=\"La Cause du Peuple\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CauseDuPeupleCDP\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-30T10:19:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/causedupeuple.net\/wp68\/wp-content\/uploads\/2026\/04\/on-toboso-massacre-justice.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Boubou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Cause_du_Peuple\" \/>\n<meta name=\"twitter:site\" content=\"@Cause_du_Peuple\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Boubou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2026\\\/04\\\/30\\\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2026\\\/04\\\/30\\\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\\\/\"},\"author\":{\"name\":\"Boubou\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#\\\/schema\\\/person\\\/ae42d63ddd0c2bab1d3835fe013e4df3\"},\"headline\":\"Parti Communiste des Philippines\u00a0: Sur le massacre de Toboso\",\"datePublished\":\"2026-04-30T10:19:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2026\\\/04\\\/30\\\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\\\/\"},\"wordCount\":1338,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2026\\\/04\\\/30\\\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/causedupeuple.net\\\/wp68\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/on-toboso-massacre-justice.png\",\"articleSection\":[\"International\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2026\\\/04\\\/30\\\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2026\\\/04\\\/30\\\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\\\/\",\"url\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2026\\\/04\\\/30\\\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\\\/\",\"name\":\"Parti Communiste des Philippines\u00a0: Sur le massacre de Toboso - La Cause du Peuple\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2026\\\/04\\\/30\\\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2026\\\/04\\\/30\\\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/causedupeuple.net\\\/wp68\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/on-toboso-massacre-justice.png\",\"datePublished\":\"2026-04-30T10:19:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2026\\\/04\\\/30\\\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2026\\\/04\\\/30\\\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2026\\\/04\\\/30\\\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\\\/#primaryimage\",\"url\":\"http:\\\/\\\/causedupeuple.net\\\/wp68\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/on-toboso-massacre-justice.png\",\"contentUrl\":\"http:\\\/\\\/causedupeuple.net\\\/wp68\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/on-toboso-massacre-justice.png\",\"width\":1024,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2026\\\/04\\\/30\\\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parti Communiste des Philippines\u00a0: Sur le massacre de Toboso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#website\",\"url\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/\",\"name\":\"La Cause du Peuple\",\"description\":\"Media prol\u00e9taire, anti-imp\u00e9rialiste et r\u00e9volutionnaire !\",\"publisher\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#organization\",\"name\":\"La Cause du Peuple\",\"url\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/causedupeuple.net\\\/wp68\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo-CDP-1ligne-blanc.png\",\"contentUrl\":\"http:\\\/\\\/causedupeuple.net\\\/wp68\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo-CDP-1ligne-blanc.png\",\"width\":1454,\"height\":200,\"caption\":\"La Cause du Peuple\"},\"image\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CauseDuPeupleCDP\",\"https:\\\/\\\/x.com\\\/Cause_du_Peuple\",\"https:\\\/\\\/www.instagram.com\\\/cause_du_peuple\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#\\\/schema\\\/person\\\/ae42d63ddd0c2bab1d3835fe013e4df3\",\"name\":\"Boubou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b27fed1dfe9dabf96a361f8dcddc7404a36838540109deea8dc5934e603399d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b27fed1dfe9dabf96a361f8dcddc7404a36838540109deea8dc5934e603399d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b27fed1dfe9dabf96a361f8dcddc7404a36838540109deea8dc5934e603399d?s=96&d=mm&r=g\",\"caption\":\"Boubou\"},\"url\":\"http:\\\/\\\/causedupeuple.net\\\/wp68\\\/author\\\/boubou\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parti Communiste des Philippines\u00a0: Sur le massacre de Toboso - La Cause du Peuple","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/","og_locale":"fr_FR","og_type":"article","og_title":"Parti Communiste des Philippines\u00a0: Sur le massacre de Toboso - La Cause du Peuple","og_description":"Nous partageons ici une traduction non officielle d&rsquo;un communiqu\u00e9 du Parti Communiste des Philippines. Marco Valbuena | Directeur de l\u2019information | Parti Communiste des Philippines | 27 avril 2026 Nous condamnons avec la plus grande fermet\u00e9 les Forces arm\u00e9es des Philippines, en particulier le 79e bataillon d\u2019infanterie, pour le massacre aveugle et disproportionn\u00e9 de 19 [&hellip;]","og_url":"https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/","og_site_name":"La Cause du Peuple","article_publisher":"https:\/\/www.facebook.com\/CauseDuPeupleCDP","article_published_time":"2026-04-30T10:19:43+00:00","og_image":[{"width":1024,"height":550,"url":"https:\/\/causedupeuple.net\/wp68\/wp-content\/uploads\/2026\/04\/on-toboso-massacre-justice.png","type":"image\/png"}],"author":"Boubou","twitter_card":"summary_large_image","twitter_creator":"@Cause_du_Peuple","twitter_site":"@Cause_du_Peuple","twitter_misc":{"\u00c9crit par":"Boubou","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/#article","isPartOf":{"@id":"https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/"},"author":{"name":"Boubou","@id":"https:\/\/causedupeuple.net\/wp68\/#\/schema\/person\/ae42d63ddd0c2bab1d3835fe013e4df3"},"headline":"Parti Communiste des Philippines\u00a0: Sur le massacre de Toboso","datePublished":"2026-04-30T10:19:43+00:00","mainEntityOfPage":{"@id":"https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/"},"wordCount":1338,"commentCount":0,"publisher":{"@id":"https:\/\/causedupeuple.net\/wp68\/#organization"},"image":{"@id":"https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/#primaryimage"},"thumbnailUrl":"http:\/\/causedupeuple.net\/wp68\/wp-content\/uploads\/2026\/04\/on-toboso-massacre-justice.png","articleSection":["International"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/","url":"https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/","name":"Parti Communiste des Philippines\u00a0: Sur le massacre de Toboso - La Cause du Peuple","isPartOf":{"@id":"https:\/\/causedupeuple.net\/wp68\/#website"},"primaryImageOfPage":{"@id":"https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/#primaryimage"},"image":{"@id":"https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/#primaryimage"},"thumbnailUrl":"http:\/\/causedupeuple.net\/wp68\/wp-content\/uploads\/2026\/04\/on-toboso-massacre-justice.png","datePublished":"2026-04-30T10:19:43+00:00","breadcrumb":{"@id":"https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/#primaryimage","url":"http:\/\/causedupeuple.net\/wp68\/wp-content\/uploads\/2026\/04\/on-toboso-massacre-justice.png","contentUrl":"http:\/\/causedupeuple.net\/wp68\/wp-content\/uploads\/2026\/04\/on-toboso-massacre-justice.png","width":1024,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/causedupeuple.net\/wp68\/2026\/04\/30\/parti-communiste-des-philippines-sur-le-massacre-de-toboso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/causedupeuple.net\/wp68\/"},{"@type":"ListItem","position":2,"name":"Parti Communiste des Philippines\u00a0: Sur le massacre de Toboso"}]},{"@type":"WebSite","@id":"https:\/\/causedupeuple.net\/wp68\/#website","url":"https:\/\/causedupeuple.net\/wp68\/","name":"La Cause du Peuple","description":"Media prol\u00e9taire, anti-imp\u00e9rialiste et r\u00e9volutionnaire !","publisher":{"@id":"https:\/\/causedupeuple.net\/wp68\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/causedupeuple.net\/wp68\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/causedupeuple.net\/wp68\/#organization","name":"La Cause du Peuple","url":"https:\/\/causedupeuple.net\/wp68\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/causedupeuple.net\/wp68\/#\/schema\/logo\/image\/","url":"http:\/\/causedupeuple.net\/wp68\/wp-content\/uploads\/2026\/03\/Logo-CDP-1ligne-blanc.png","contentUrl":"http:\/\/causedupeuple.net\/wp68\/wp-content\/uploads\/2026\/03\/Logo-CDP-1ligne-blanc.png","width":1454,"height":200,"caption":"La Cause du Peuple"},"image":{"@id":"https:\/\/causedupeuple.net\/wp68\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CauseDuPeupleCDP","https:\/\/x.com\/Cause_du_Peuple","https:\/\/www.instagram.com\/cause_du_peuple\/"]},{"@type":"Person","@id":"https:\/\/causedupeuple.net\/wp68\/#\/schema\/person\/ae42d63ddd0c2bab1d3835fe013e4df3","name":"Boubou","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5b27fed1dfe9dabf96a361f8dcddc7404a36838540109deea8dc5934e603399d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b27fed1dfe9dabf96a361f8dcddc7404a36838540109deea8dc5934e603399d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b27fed1dfe9dabf96a361f8dcddc7404a36838540109deea8dc5934e603399d?s=96&d=mm&r=g","caption":"Boubou"},"url":"http:\/\/causedupeuple.net\/wp68\/author\/boubou\/"}]}},"jetpack_featured_media_url":"http:\/\/causedupeuple.net\/wp68\/wp-content\/uploads\/2026\/04\/on-toboso-massacre-justice.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/posts\/38525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/comments?post=38525"}],"version-history":[{"count":0,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/posts\/38525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/media\/38592"}],"wp:attachment":[{"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/media?parent=38525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/categories?post=38525"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/tags?post=38525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}