{"id":6599,"date":"2022-10-06T13:42:48","date_gmt":"2022-10-06T12:42:48","guid":{"rendered":"http:\/\/causedupeuple.net\/wp68\/?p=6599"},"modified":"2022-10-06T13:53:12","modified_gmt":"2022-10-06T12:53:12","slug":"les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise","status":"publish","type":"post","link":"http:\/\/causedupeuple.net\/wp68\/2022\/10\/06\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\/","title":{"rendered":"Les nations opprim\u00e9es portent le fardeau le plus lourd dans l&rsquo;aggravation de la crise"},"content":{"rendered":"<p><span class=\"JsGRdQ\">Depuis avril, les masses au Sri Lanka ont lutt\u00e9 contre le gouvernement pourri de propri\u00e9taires terriens. Apr\u00e8s des mois d&rsquo;inflation record, de pannes d&rsquo;\u00e9lectricit\u00e9 et de p\u00e9nurie de nourriture, de m\u00e9dicaments et de carburant, des manifestations explosives ont \u00e9clat\u00e9.<\/span> <span class=\"JsGRdQ\">(<\/span><span class=\"JsGRdQ\">Extraits et traduction non officielle tir\u00e9e du site ci-ic.org.)<\/span><\/p>\n<p><span class=\"JsGRdQ\">D\u00e9j\u00e0 en avril, le gouvernement a d\u00e9clar\u00e9 l&rsquo;\u00e9tat d&rsquo;urgence et a r\u00e9pondu par la violence, mais cela n&rsquo;a pas pu r\u00e9primer les protestations. En juillet, les masses s&#8217;empar\u00e8rent de la maison et des bureaux pr\u00e9sidentiels, incendi\u00e8rent la r\u00e9sidence du Premier ministre et exig\u00e8rent la d\u00e9mission du pr\u00e9sident. Le pr\u00e9sident a fui le pays, et un nouveau \u2013 le Premier ministre, qui pendant des ann\u00e9es a \u00e9t\u00e9 aussi responsable que le pr\u00e9sident des politiques de vente de pays du gouvernement \u2013 \u200b\u200ba \u00e9t\u00e9 choisi. Ranil Wikremengsinghe \u00e9tait auparavant \u00ab\u00a0soutien\u00a0\u00bb aux manifestations, mais a montr\u00e9 sa vraie nature plus tard, avec de violentes r\u00e9pressions et des arrestations de dirigeants de la manifestation. [&#8230;]<\/span><\/p>\n<p><span class=\"JsGRdQ\">Les \u00e9v\u00e9nements qui se d\u00e9roulent au Sri Lanka sont une expression de l&rsquo;aggravation de la crise g\u00e9n\u00e9rale de l&rsquo;imp\u00e9rialisme, de la crise \u00e9conomique ou de la crise de surproduction, ainsi que de la crise politique. De grandes manifestations contre des gouvernements de diff\u00e9rentes couleurs se produisent partout dans le monde, par exemple dans des pays opprim\u00e9s comme l&rsquo;Iran, l&rsquo;Argentine, le Panama et l&rsquo;Albanie, dans la Chine social-imp\u00e9rialiste et dans des pays imp\u00e9rialistes comme les Pays-Bas, les gouvernements essayant de maintenir l&rsquo;ordre par la violence r\u00e9actionnaire. Surtout dans les pays opprim\u00e9s par l&rsquo;imp\u00e9rialisme, les gens souffrent intens\u00e9ment, comme on peut le voir dans l&rsquo;exemple du Sri Lanka, mais aussi dans les pays imp\u00e9rialistes, la classe ouvri\u00e8re voit comment son salaire durement gagn\u00e9 continue de diminuer relativement et la vie devient de plus en plus pr\u00e9caire. La situation r\u00e9volutionnaire se d\u00e9veloppe de mani\u00e8re in\u00e9gale dans le monde entier. [&#8230;]<\/span><\/p>\n<p><span class=\"JsGRdQ\">[Le Sri Lanka] est une semi-colonie, avec son processus \u00e9conomique contr\u00f4l\u00e9 par les imp\u00e9rialistes. Le gouvernement du Sri Lanka suit depuis des d\u00e9cennies la politique impos\u00e9e par l&rsquo;imp\u00e9rialisme yankee et s&rsquo;endette de plus en plus \u00e0 l&rsquo;ext\u00e9rieur, c&rsquo;est-\u00e0-dire le capital imp\u00e9rialiste, et, avec l&rsquo;aggravation de la crise, il est devenu incapable de payer la dette, c&rsquo;est-\u00e0-dire , il est devenu incapable de fournir des profits suffisants \u00e0 ses ma\u00eetres imp\u00e9rialistes par le paiement du principal et des int\u00e9r\u00eats, etc. et devra payer davantage par ren\u00e9gociation ou consolidation de la dette, hypoth\u00e9quant davantage le pays. Les principaux d\u00e9tenteurs de la dette sont des institutions financi\u00e8res yankees et des instruments comme la Banque mondiale en collusion et en lutte avec le social-imp\u00e9rialisme chinois. Les imp\u00e9rialismes britannique, allemand et japonais ont aussi leur part.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Or, le FMI, instrument de l&rsquo;imp\u00e9rialisme yankee, vient d&rsquo;annoncer un pr\u00eat de 2,9 milliards de dollars au Sri Lanka pour lui permettre de traverser la crise la plus aigu\u00eb. En \u00e9change, le gouvernement sri-lankais s&rsquo;engage \u00e0 effectuer des changements de politique \u00e9conomique. Par des n\u00e9gociations, les imp\u00e9rialistes renforcent leur contr\u00f4le sur le pays, \u00e9galement en ce qui concerne les autres imp\u00e9rialistes.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">La monnaie sri-lankaise a chut\u00e9 de 80 %, rendant les importations plus ch\u00e8res et provoquant la mis\u00e8re du peuple. De plus, les restrictions de voyage pendant la pand\u00e9mie ont nui \u00e0 l&rsquo;industrie du tourisme, et les cons\u00e9quences de l&rsquo;agression imp\u00e9rialiste de la Russie contre l&rsquo;Ukraine et les sanctions contre la Russie impos\u00e9es par l&rsquo;imp\u00e9rialisme yankee, la seule superpuissance h\u00e9g\u00e9monique au monde aujourd&rsquo;hui. [&#8230;]<\/span><\/p>\n<p><span class=\"JsGRdQ\">La bourgeoisie s&rsquo;accroche au pouvoir par tous les moyens, mais elle montre aussi qu&rsquo;elle est faible, m\u00eame dans les pays imp\u00e9rialistes, elle ne peut pas continuer \u00e0 soudoyer la classe ouvri\u00e8re comme elle l&rsquo;a fait, alors que des masses de plus en plus larges sont pouss\u00e9es vers des conditions de plus en plus d\u00e9sastreuses, dans pays opprim\u00e9s, il montre comment chaque r\u00e9gime, malgr\u00e9 ses promesses, sert les imp\u00e9rialistes, l&rsquo;imp\u00e9rialisme ne peut qu&rsquo;offrir plus de souffrance, plus de guerre et de faim \u00e0 la grande majorit\u00e9 des peuples du monde. Comme indiqu\u00e9 pr\u00e9c\u00e9demment, partout dans le monde, nous voyons l&rsquo;activit\u00e9 croissante des masses, avec de puissantes protestations qui \u00e9clatent. Et partout il y a des luttes qui ne font pas irruption dans les m\u00e9dias bourgeois, il y a des luttes quotidiennes, silencieuses mais puissantes, des masses en qu\u00eate de direction. [&#8230;]<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Il a \u00e9t\u00e9 clairement d\u00e9montr\u00e9 que les probl\u00e8mes profond\u00e9ment enracin\u00e9s dans l&rsquo;oppression imp\u00e9rialiste ne seront pas r\u00e9solus par un changement de r\u00e9gime. Il est \u00e9galement d\u00e9montr\u00e9 que malgr\u00e9 la lutte h\u00e9ro\u00efque des masses, sans la direction du parti communiste, le mouvement n&rsquo;est pas en mesure d&rsquo;unir v\u00e9ritablement le peuple contre l&rsquo;imp\u00e9rialisme. [&#8230;]<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Par cons\u00e9quent, ce qui nous attend est la t\u00e2che de lutter contre l&rsquo;imp\u00e9rialisme, le capitalisme bureaucratique et le semi-f\u00e9odalisme dans les pays opprim\u00e9s, et dans les pays imp\u00e9rialistes, de lutter pour les revendications des masses et contre les attaques de la bourgeoisie, et d&rsquo;unir ces luttes avec la lutte pour le pouvoir, la lutte pour la constitution ou la reconstitution des partis communistes dans chaque pays en tant que partis marxistes-l\u00e9ninistes-mao\u00efstes, principalement mao\u00efstes, militaris\u00e9s, pour initier de nouvelles guerres populaires.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis avril, les masses au Sri Lanka ont lutt\u00e9 contre le gouvernement pourri de propri\u00e9taires terriens. Apr\u00e8s des mois d&rsquo;inflation record, de pannes d&rsquo;\u00e9lectricit\u00e9 et de p\u00e9nurie de nourriture, de m\u00e9dicaments et de carburant, des manifestations explosives ont \u00e9clat\u00e9. (Extraits et traduction non officielle tir\u00e9e du site ci-ic.org.) D\u00e9j\u00e0 en avril, le gouvernement a d\u00e9clar\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-6599","post","type-post","status-publish","format-standard","hentry","category-international"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les nations opprim\u00e9es portent le fardeau le plus lourd dans l&#039;aggravation de la crise - La Cause du Peuple<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/causedupeuple.net\/wp68\/2022\/10\/06\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les nations opprim\u00e9es portent le fardeau le plus lourd dans l&#039;aggravation de la crise - La Cause du Peuple\" \/>\n<meta property=\"og:description\" content=\"Depuis avril, les masses au Sri Lanka ont lutt\u00e9 contre le gouvernement pourri de propri\u00e9taires terriens. Apr\u00e8s des mois d&rsquo;inflation record, de pannes d&rsquo;\u00e9lectricit\u00e9 et de p\u00e9nurie de nourriture, de m\u00e9dicaments et de carburant, des manifestations explosives ont \u00e9clat\u00e9. (Extraits et traduction non officielle tir\u00e9e du site ci-ic.org.) D\u00e9j\u00e0 en avril, le gouvernement a d\u00e9clar\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/causedupeuple.net\/wp68\/2022\/10\/06\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\/\" \/>\n<meta property=\"og:site_name\" content=\"La Cause du Peuple\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CauseDuPeupleCDP\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-06T12:42:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-06T12:53:12+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Cause_du_Peuple\" \/>\n<meta name=\"twitter:site\" content=\"@Cause_du_Peuple\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2022\\\/10\\\/06\\\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2022\\\/10\\\/06\\\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#\\\/schema\\\/person\\\/f3b7dbea0c4e298ac650372815102bec\"},\"headline\":\"Les nations opprim\u00e9es portent le fardeau le plus lourd dans l&rsquo;aggravation de la crise\",\"datePublished\":\"2022-10-06T12:42:48+00:00\",\"dateModified\":\"2022-10-06T12:53:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2022\\\/10\\\/06\\\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\\\/\"},\"wordCount\":982,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#organization\"},\"articleSection\":[\"International\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2022\\\/10\\\/06\\\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2022\\\/10\\\/06\\\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\\\/\",\"url\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2022\\\/10\\\/06\\\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\\\/\",\"name\":\"Les nations opprim\u00e9es portent le fardeau le plus lourd dans l'aggravation de la crise - La Cause du Peuple\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#website\"},\"datePublished\":\"2022-10-06T12:42:48+00:00\",\"dateModified\":\"2022-10-06T12:53:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2022\\\/10\\\/06\\\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2022\\\/10\\\/06\\\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/2022\\\/10\\\/06\\\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les nations opprim\u00e9es portent le fardeau le plus lourd dans l&rsquo;aggravation de la crise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#website\",\"url\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/\",\"name\":\"La Cause du Peuple\",\"description\":\"Media prol\u00e9taire, anti-imp\u00e9rialiste et r\u00e9volutionnaire !\",\"publisher\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#organization\",\"name\":\"La Cause du Peuple\",\"url\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/causedupeuple.net\\\/wp68\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo-CDP-1ligne-blanc.png\",\"contentUrl\":\"http:\\\/\\\/causedupeuple.net\\\/wp68\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo-CDP-1ligne-blanc.png\",\"width\":1454,\"height\":200,\"caption\":\"La Cause du Peuple\"},\"image\":{\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CauseDuPeupleCDP\",\"https:\\\/\\\/x.com\\\/Cause_du_Peuple\",\"https:\\\/\\\/www.instagram.com\\\/cause_du_peuple\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/causedupeuple.net\\\/wp68\\\/#\\\/schema\\\/person\\\/f3b7dbea0c4e298ac650372815102bec\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/391cf28cbd320a328f6c1257ca2777cfc572672d0187ca7d10d410428b810794?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/391cf28cbd320a328f6c1257ca2777cfc572672d0187ca7d10d410428b810794?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/391cf28cbd320a328f6c1257ca2777cfc572672d0187ca7d10d410428b810794?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"http:\\\/\\\/causedupeuple.net\\\/wp68\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les nations opprim\u00e9es portent le fardeau le plus lourd dans l'aggravation de la crise - La Cause du Peuple","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/causedupeuple.net\/wp68\/2022\/10\/06\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\/","og_locale":"fr_FR","og_type":"article","og_title":"Les nations opprim\u00e9es portent le fardeau le plus lourd dans l'aggravation de la crise - La Cause du Peuple","og_description":"Depuis avril, les masses au Sri Lanka ont lutt\u00e9 contre le gouvernement pourri de propri\u00e9taires terriens. Apr\u00e8s des mois d&rsquo;inflation record, de pannes d&rsquo;\u00e9lectricit\u00e9 et de p\u00e9nurie de nourriture, de m\u00e9dicaments et de carburant, des manifestations explosives ont \u00e9clat\u00e9. (Extraits et traduction non officielle tir\u00e9e du site ci-ic.org.) D\u00e9j\u00e0 en avril, le gouvernement a d\u00e9clar\u00e9 [&hellip;]","og_url":"https:\/\/causedupeuple.net\/wp68\/2022\/10\/06\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\/","og_site_name":"La Cause du Peuple","article_publisher":"https:\/\/www.facebook.com\/CauseDuPeupleCDP","article_published_time":"2022-10-06T12:42:48+00:00","article_modified_time":"2022-10-06T12:53:12+00:00","author":"admin","twitter_card":"summary_large_image","twitter_creator":"@Cause_du_Peuple","twitter_site":"@Cause_du_Peuple","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/causedupeuple.net\/wp68\/2022\/10\/06\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\/#article","isPartOf":{"@id":"https:\/\/causedupeuple.net\/wp68\/2022\/10\/06\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\/"},"author":{"name":"admin","@id":"https:\/\/causedupeuple.net\/wp68\/#\/schema\/person\/f3b7dbea0c4e298ac650372815102bec"},"headline":"Les nations opprim\u00e9es portent le fardeau le plus lourd dans l&rsquo;aggravation de la crise","datePublished":"2022-10-06T12:42:48+00:00","dateModified":"2022-10-06T12:53:12+00:00","mainEntityOfPage":{"@id":"https:\/\/causedupeuple.net\/wp68\/2022\/10\/06\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\/"},"wordCount":982,"commentCount":0,"publisher":{"@id":"https:\/\/causedupeuple.net\/wp68\/#organization"},"articleSection":["International"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/causedupeuple.net\/wp68\/2022\/10\/06\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/causedupeuple.net\/wp68\/2022\/10\/06\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\/","url":"https:\/\/causedupeuple.net\/wp68\/2022\/10\/06\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\/","name":"Les nations opprim\u00e9es portent le fardeau le plus lourd dans l'aggravation de la crise - La Cause du Peuple","isPartOf":{"@id":"https:\/\/causedupeuple.net\/wp68\/#website"},"datePublished":"2022-10-06T12:42:48+00:00","dateModified":"2022-10-06T12:53:12+00:00","breadcrumb":{"@id":"https:\/\/causedupeuple.net\/wp68\/2022\/10\/06\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/causedupeuple.net\/wp68\/2022\/10\/06\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/causedupeuple.net\/wp68\/2022\/10\/06\/les-nations-opprimees-portent-le-fardeau-le-plus-lourd-dans-laggravation-de-la-crise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/causedupeuple.net\/wp68\/"},{"@type":"ListItem","position":2,"name":"Les nations opprim\u00e9es portent le fardeau le plus lourd dans l&rsquo;aggravation de la crise"}]},{"@type":"WebSite","@id":"https:\/\/causedupeuple.net\/wp68\/#website","url":"https:\/\/causedupeuple.net\/wp68\/","name":"La Cause du Peuple","description":"Media prol\u00e9taire, anti-imp\u00e9rialiste et r\u00e9volutionnaire !","publisher":{"@id":"https:\/\/causedupeuple.net\/wp68\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/causedupeuple.net\/wp68\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/causedupeuple.net\/wp68\/#organization","name":"La Cause du Peuple","url":"https:\/\/causedupeuple.net\/wp68\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/causedupeuple.net\/wp68\/#\/schema\/logo\/image\/","url":"http:\/\/causedupeuple.net\/wp68\/wp-content\/uploads\/2026\/03\/Logo-CDP-1ligne-blanc.png","contentUrl":"http:\/\/causedupeuple.net\/wp68\/wp-content\/uploads\/2026\/03\/Logo-CDP-1ligne-blanc.png","width":1454,"height":200,"caption":"La Cause du Peuple"},"image":{"@id":"https:\/\/causedupeuple.net\/wp68\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CauseDuPeupleCDP","https:\/\/x.com\/Cause_du_Peuple","https:\/\/www.instagram.com\/cause_du_peuple\/"]},{"@type":"Person","@id":"https:\/\/causedupeuple.net\/wp68\/#\/schema\/person\/f3b7dbea0c4e298ac650372815102bec","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/391cf28cbd320a328f6c1257ca2777cfc572672d0187ca7d10d410428b810794?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/391cf28cbd320a328f6c1257ca2777cfc572672d0187ca7d10d410428b810794?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/391cf28cbd320a328f6c1257ca2777cfc572672d0187ca7d10d410428b810794?s=96&d=mm&r=g","caption":"admin"},"url":"http:\/\/causedupeuple.net\/wp68\/author\/admin\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/posts\/6599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/comments?post=6599"}],"version-history":[{"count":0,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/posts\/6599\/revisions"}],"wp:attachment":[{"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/media?parent=6599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/categories?post=6599"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/causedupeuple.net\/wp68\/wp-json\/wp\/v2\/tags?post=6599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}